{"id":11842,"date":"2023-02-19T15:39:00","date_gmt":"2023-02-19T15:39:00","guid":{"rendered":"https:\/\/www.safes.so\/blogs\/discipline-a-child-without-hitting\/"},"modified":"2023-07-25T08:44:00","modified_gmt":"2023-07-25T08:44:00","slug":"discipline-a-child-without-hitting","status":"publish","type":"post","link":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/","title":{"rendered":"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p><span data-contrast=\"auto\">Seien wir ehrlich: Einige von uns wurden fr\u00fcher von unseren Eltern geschlagen. Und wenn nicht wir, wurden unsere Eltern von ihren Eltern geschlagen, wenn sie sich schlecht benahmen. Es war damals eine \u00fcbliche Disziplinarma\u00dfnahme.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Heutzutage ist alles anders. Ihr Kind zu schlagen oder anzuschreien ist nicht mehr akzeptabel. Und das ist zum Besseren. In diesem Blog werden wir dar\u00fcber sprechen, warum es falsch ist, mit Ihren Kindern k\u00f6rperlich aggressiv zu werden, und f\u00fcnf M\u00f6glichkeiten vorschlagen, ein Kind zu disziplinieren, ohne es zu schlagen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 aria-level=\"2\"><span data-contrast=\"none\">Warum Sie Ihr Kind nicht schlagen oder anschreien sollten<\/span><\/h2>\n<p><span data-contrast=\"auto\">Kinder k\u00f6nnen manchmal wirklich Ihre Kn\u00f6pfe dr\u00fccken. Sie w\u00fcrden Dinge tun, die dich dazu bringen, aus voller Kehle zu schreien. Aber schreien oder schlagen ist nie die Antwort. In der Lage zu sein, mit Ihren Emotionen umzugehen und Ihren Kindern ein positives Beispiel zu geben, sind wichtige Aspekte der Elternschaft. Lesen Sie, <\/span><a href=\"https:\/\/www.safes.so\/blogs\/parents-influence-kids-behavior\/\"><span data-contrast=\"none\">wie Eltern das Verhalten ihrer Kinder im Zeitalter des Internets beeinflussen?<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Es gibt Beweise daf\u00fcr, dass Schreien und Entt\u00e4uschung mit <\/span><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC2888480\/pdf\/nihms-198378.pdf\"><span data-contrast=\"none\">erh\u00f6hter k\u00f6rperlicher und verbaler Aggression<\/span><\/a><span data-contrast=\"auto\"> bei Kindern verbunden sind. Dar\u00fcber hinaus kann es zur Entwicklung von Angstsymptomen in ihnen beitragen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">K\u00f6rperliche Z\u00fcchtigung hingegen hat sich als wirksam erwiesen, um <\/span><a href=\"https:\/\/scholarship.law.duke.edu\/cgi\/viewcontent.cgi?referer=&amp;httpsredir=1&amp;article=1565&amp;context=lcp\"><span data-contrast=\"none\">das Verhalten eines Kindes kurzfristig zu \u00e4ndern.<\/span><\/a><span data-contrast=\"auto\"> Diese Verhaltens\u00e4nderung r\u00fchrt jedoch von der Angst der Kinder vor k\u00f6rperlichen Schmerzen her, anstatt zu verstehen, warum ihre Handlungen falsch sind.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">K\u00f6rperliche Z\u00fcchtigung hat auch langfristige Auswirkungen auf Kinder. In ihrer Richtlinie &#8222;<\/span><a href=\"https:\/\/publications.aap.org\/pediatrics\/article\/142\/6\/e20183112\/37452\/Effective-Discipline-to-Raise-Healthy-Children?autologincheck=redirected\"><span data-contrast=\"none\">Effektive Disziplin zur Erziehung gesunder Kinder<\/span><\/a><span data-contrast=\"auto\">&#8220; weist die American Academy of Pediatrics darauf hin, dass das Schlagen von Kindern ihr Risiko f\u00fcr Aggressionen und die Entwicklung psychischer St\u00f6rungen in der Zukunft erh\u00f6ht.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Abgesehen von der Tatsache, dass Kindesmissbrauch\u00a0 in den USA seit 1974 illegal ist, sollte das Schreien und Schlagen von Kindern um jeden Preis vermieden werden, da sie eine Bedrohung f\u00fcr das Wohlergehen von Kindern darstellen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-11584\" src=\"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/How-to-discipline-a-child-without-yelling-or-hitting.jpg\" alt=\"Angry stressed mother yelling at teen girl\" width=\"1200\" height=\"600\" srcset=\"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/How-to-discipline-a-child-without-yelling-or-hitting.jpg 1200w, https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/How-to-discipline-a-child-without-yelling-or-hitting-300x150.jpg 300w, https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/How-to-discipline-a-child-without-yelling-or-hitting-1024x512.jpg 1024w, https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/How-to-discipline-a-child-without-yelling-or-hitting-768x384.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2 aria-level=\"2\"><span data-contrast=\"none\">Wie man ein Kind diszipliniert, ohne zu schreien oder zu schlagen<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:40,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h2>\n<p><span data-contrast=\"auto\">Die folgenden f\u00fcnf Optionen sind bessere Alternativen zu Spanking oder jeder anderen Form k\u00f6rperlicher Gewalt:<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<h3 aria-level=\"3\"><span data-contrast=\"none\">Unterrichten Sie sie \u00fcber Konsequenzen<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:40,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Schon mal was vom Dominoeffekt geh\u00f6rt? Es bedeutet, dass alle Ereignisse konsequent miteinander verbunden sind. In einfacheren Worten impliziert es, dass jede Handlung, die wir unternehmen, Konsequenzen hat. Diese Folgen k\u00f6nnen gut oder schlecht sein, abh\u00e4ngig von der Art der ersten Handlung.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Eine der M\u00f6glichkeiten, wie Sie Ihr Kind effektiv disziplinieren k\u00f6nnen, besteht darin, es \u00fcber die Ergebnisse seiner Handlungen zu unterrichten. Haben sie Spielzeug kaputt gemacht? Sie werden f\u00fcr eine Weile keine neuen bekommen. Bleiben sie oft nach der Ausgangssperre wach und surfen auf ihren Handys? <\/span><a href=\"https:\/\/www.safes.so\/blogs\/how-to-shut-off-the-internet-at-night-for-better-sleep-at-home\/\"><span data-contrast=\"none\">Das Internet wird nachts abgeschaltet<\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Durch die Implementierung dieses Ansatzes ist es weniger wahrscheinlich, dass sie es pers\u00f6nlich nehmen, wenn etwas nicht so l\u00e4uft, wie sie es wollen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 aria-level=\"3\"><span data-contrast=\"none\">Geben Sie ihnen eine Auszeit<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:40,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Eine Auszeit bezieht sich darauf, wenn ein Kind von dem urspr\u00fcnglichen Ort, an dem es sich schlecht benommen hat, entfernt und an einen isolierten Ort gebracht wird. W\u00e4hrend einer Auszeit darf Ihr Kind den vorgesehenen Ort nicht verlassen und andere Aktivit\u00e4ten ausf\u00fchren. Diese Zeit sollte der Beruhigung und Reflexion ihres Verhaltens gewidmet sein.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Eine Auszeit soll nicht lange dauern. Erw\u00e4gen Sie, Ihrem Kind nur ein paar Minuten Auszeit zu geben. Seien Sie auch fest und versuchen Sie, keine Ausreden zu finden.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Die Auszeit richtet sich traditionell an Kleinkinder. Es gibt jedoch eine <\/span><a href=\"https:\/\/johngallagherphd.com\/wp-content\/uploads\/2020\/03\/Time-outs_For_Teens.pdf\"><span data-contrast=\"none\">Studie<\/span><\/a><span data-contrast=\"auto\">, die darauf hindeutet, dass eine Auszeit auch f\u00fcr Jugendliche von bis zu 18 oder 19 Jahren wirksam sein kann. Es liegt jedoch an Ihnen zu entscheiden, ob es f\u00fcr Ihr Kind geeignet ist. Wenn Sie sich entscheiden, dass dies nicht der Fall ist, probieren Sie die anderen Optionen aus.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 aria-level=\"3\"><span data-contrast=\"none\">Hausarrest<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:40,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Ein Kind unter Hausarrest zu stellen bedeutet, ihm f\u00fcr einen begrenzten Zeitraum den Zugang zu bestimmten Privilegien zu entziehen. Dies geschieht, weil es etwas getan hat, was es nicht h\u00e4tten tun sollen. Es gibt ein paar Punkte, die bei der Hausarrest eines Kindes beachtet werden sollten:<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Erstens m\u00fcssen die Grundregeln und Erwartungen klar definiert sein. Sie sollten Ihrem Kind klare Anweisungen geben, warum es unter Hausarrest gestellt wird, was in dieser Zeit nicht erlaubt ist und was Sie von ihm erwarten.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Zweitens sollte die Schwere der Strafe in einem angemessenen Verh\u00e4ltnis zu der Tat stehen. <\/span><i><span data-contrast=\"auto\">Die Strafe sollte zum Verbrechen passen<\/span><\/i><span data-contrast=\"auto\">, wie das Sprichwort sagt. Zu strenge Regeln aufzustellen oder ein Kind zu oft unter Hausarrest zu stellen, wird wahrscheinlich nach hinten losgehen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Drittens, halten Sie es relativ. Stellen Sie sicher, dass das, was Sie von Ihrem Kind unter Hausarrest leugnen, eine Folge seiner Handlungen ist. Wenn sie zum Beispiel sp\u00e4t nach Hause gekommen sind, sagen Sie ihnen nicht, dass sie am Wochenende nicht fernsehen k\u00f6nnen. Das wird sie dazu bringen, noch mehr auszugehen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 aria-level=\"3\"><span data-contrast=\"none\">Beschr\u00e4nken Sie ihren Zugriff auf das Internet<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:40,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Heutzutage ist der beste Weg, ein Kind zu disziplinieren, wenn es sich verh\u00e4lt, seinen Zugang zum Internet zu unterbrechen. Das Internet ist der moderne Kindermagnet. Kinder verbringen jeden Tag mehr und mehr Zeit damit, soziale Medien und andere Online-Plattformen zu durchsuchen. Abgesehen davon, dass sie Menschen aus der ganzen Welt verbinden,<\/span><a href=\"https:\/\/www.safes.so\/blogs\/social-media-is-more-harmful-than-beneficial\/\"> <span data-contrast=\"none\">k\u00f6nnen soziale Medien manchmal mehr sch\u00e4dlich als n\u00fctzlich sein<\/span><\/a><span data-contrast=\"auto\">. Au\u00dferdem ist es f\u00fcr Kinder so wichtig geworden, dass die Einschr\u00e4nkung ihres Zugangs f\u00fcr eine Weile dazu f\u00fchren kann, dass sie sich wirklich verhalten und vermeiden, die gleichen Fehler zu wiederholen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.safes.so\/\"><span data-contrast=\"none\">Safes<\/span><\/a><span data-contrast=\"auto\"> k\u00f6nnen in solchen Situationen eine gro\u00dfe Hilfe sein. Es ist eine Kindersicherungs-App, mit der Sie die Online-Aktivit\u00e4ten Ihrer Kinder \u00fcberwachen k\u00f6nnen. Es hilft Ihnen auch, den Zugriff auf Apps zu blockieren oder einzuschr\u00e4nken. und es kann auf <\/span><a href=\"https:\/\/apps.apple.com\/ae\/app\/parental-control-app-safes\/id1611890499?utm_source=Blog+DL+Link&amp;utm_medium=organic&amp;utm_campaign=Blog+Download+Links+Tracker&amp;utm_content=ios\"><span data-contrast=\"none\">iOS,<\/span><\/a> <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=de.sternx.safes&amp;referrer=utm_source%3DBlog%2520DL%2520Link%26utm_medium%3Dorganic%26utm_content%3Dandroid%26utm_campaign%3DBlog%2520Download%2520Links%2520Tracker\"><span data-contrast=\"none\">Android<\/span><\/a><span data-contrast=\"auto\"> und <\/span><a href=\"https:\/\/www.safes.so\/blogs\/resources\/windows-10\/\"><span data-contrast=\"none\">Windows<\/span><\/a><span data-contrast=\"auto\"> installiert werden. Einer der Vorteile der Verwendung von Safes ist, dass Sie auch herausfinden k\u00f6nnen, ob negative Einfl\u00fcsse von Social Media dazu f\u00fchren, dass sie sich schlecht verhalten.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3 aria-level=\"3\"><span data-contrast=\"none\">Ermutigen Sie gutes Verhalten<\/span><span data-ccp-props=\"{&quot;134245418&quot;:true,&quot;134245529&quot;:true,&quot;201341983&quot;:0,&quot;335559738&quot;:40,&quot;335559739&quot;:0,&quot;335559740&quot;:259}\">\u00a0<\/span><\/h3>\n<p><span data-contrast=\"auto\">Bei der Disziplinierung Ihres Kindes geht es nicht immer darum, seine Fehler zu tadeln. Es geht auch darum, ihr positives Verhalten zu belohnen. Das kann im Alltag \u00fcbersehen werden. Sie sollten sich also bem\u00fchen, sich daran zu erinnern, sie zu ermutigen, wenn sie etwas Gutes tun. Denken Sie daran, dass, obwohl verbale Best\u00e4tigung entscheidend ist, Sie sie gelegentlich auch mit etwas Greifbarerem belohnen sollten, wie einem Geschenk oder einem Tag, den Sie drau\u00dfen verbringen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2 aria-level=\"2\"><span data-contrast=\"none\">Schlussfolgerung<\/span><\/h2>\n<p><span data-contrast=\"auto\">Manchmal k\u00f6nnen Kinder Sie dazu bringen, eine Sicherung zu durchbrennen. Aber Misshandlung ist kein guter Weg, um Ihre Kinder zu erziehen. Es gibt andere M\u00f6glichkeiten, ein Kind zu disziplinieren, ohne es zu schlagen, von denen wir einige oben erw\u00e4hnt haben. Anstatt Ihren Kindern gegen\u00fcber gewaltt\u00e4tig zu sein, sollten Sie versuchen, Ihre Wut einzud\u00e4mmen und konstruktivere Wege zu gehen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier sind die Gr\u00fcnde daf\u00fcr, zusammen mit M\u00f6glichkeiten, ein Kind ohne Gewalt zu erziehen.<\/p>\n","protected":false},"author":9,"featured_media":11583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[80],"tags":[],"class_list":["post-11842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips-for-parents-de-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen<\/title>\n<meta name=\"description\" content=\"Ever wonder why your ancestors\u2019 method of hitting their children didn\u2019t work? Here\u2019s why, along with ways to discipline a child without hitting them.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen\" \/>\n<meta property=\"og:description\" content=\"Ever wonder why your ancestors\u2019 method of hitting their children didn\u2019t work? Here\u2019s why, along with ways to discipline a child without hitting them.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/\" \/>\n<meta property=\"og:site_name\" content=\"Screentime Monitoring | Safes Parental Control App\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/safesfamily\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-19T15:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T08:44:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mahsa Naseri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mahsa Naseri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/\"},\"author\":{\"name\":\"Mahsa Naseri\",\"@id\":\"https:\/\/www.safes.so\/de\/#\/schema\/person\/64b618a9ae4e2564f5be7ee8f5308a68\"},\"headline\":\"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen\",\"datePublished\":\"2023-02-19T15:39:00+00:00\",\"dateModified\":\"2023-07-25T08:44:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/\"},\"wordCount\":1159,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.safes.so\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg\",\"articleSection\":[\"Tipps f\u00fcr Eltern\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/\",\"url\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/\",\"name\":\"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen\",\"isPartOf\":{\"@id\":\"https:\/\/www.safes.so\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg\",\"datePublished\":\"2023-02-19T15:39:00+00:00\",\"dateModified\":\"2023-07-25T08:44:00+00:00\",\"description\":\"Ever wonder why your ancestors\u2019 method of hitting their children didn\u2019t work? Here\u2019s why, along with ways to discipline a child without hitting them.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage\",\"url\":\"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg\",\"contentUrl\":\"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg\",\"width\":1200,\"height\":600,\"caption\":\"Little girl crying on the floor\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.safes.so\/de\/#website\",\"url\":\"https:\/\/www.safes.so\/de\/\",\"name\":\"Screentime Monitoring | Safes Parental Control App\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.safes.so\/de\/#organization\"},\"alternateName\":\"Safes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.safes.so\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.safes.so\/de\/#organization\",\"name\":\"Safes Parental Control App\",\"alternateName\":\"Safes\",\"url\":\"https:\/\/www.safes.so\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.safes.so\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.safes.so\/wp-content\/uploads\/2022\/06\/11.webp\",\"contentUrl\":\"https:\/\/www.safes.so\/wp-content\/uploads\/2022\/06\/11.webp\",\"width\":240,\"height\":240,\"caption\":\"Safes Parental Control App\"},\"image\":{\"@id\":\"https:\/\/www.safes.so\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/safesfamily\",\"https:\/\/www.linkedin.com\/company\/safesparentalcontrol\/\",\"https:\/\/www.youtube.com\/@SafesApp\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.safes.so\/de\/#\/schema\/person\/64b618a9ae4e2564f5be7ee8f5308a68\",\"name\":\"Mahsa Naseri\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.safes.so\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a4c96c3c2a06eab858a973b582c68a87?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a4c96c3c2a06eab858a973b582c68a87?s=96&d=mm&r=g\",\"caption\":\"Mahsa Naseri\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen","description":"Ever wonder why your ancestors\u2019 method of hitting their children didn\u2019t work? Here\u2019s why, along with ways to discipline a child without hitting them.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/","og_locale":"de_DE","og_type":"article","og_title":"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen","og_description":"Ever wonder why your ancestors\u2019 method of hitting their children didn\u2019t work? Here\u2019s why, along with ways to discipline a child without hitting them.","og_url":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/","og_site_name":"Screentime Monitoring | Safes Parental Control App","article_publisher":"https:\/\/www.facebook.com\/safesfamily","article_published_time":"2023-02-19T15:39:00+00:00","article_modified_time":"2023-07-25T08:44:00+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg","type":"image\/jpeg"}],"author":"Mahsa Naseri","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mahsa Naseri","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#article","isPartOf":{"@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/"},"author":{"name":"Mahsa Naseri","@id":"https:\/\/www.safes.so\/de\/#\/schema\/person\/64b618a9ae4e2564f5be7ee8f5308a68"},"headline":"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen","datePublished":"2023-02-19T15:39:00+00:00","dateModified":"2023-07-25T08:44:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/"},"wordCount":1159,"commentCount":0,"publisher":{"@id":"https:\/\/www.safes.so\/de\/#organization"},"image":{"@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage"},"thumbnailUrl":"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg","articleSection":["Tipps f\u00fcr Eltern"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/","url":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/","name":"5 Ans\u00e4tze, Kinder gewaltfrei zu erziehen","isPartOf":{"@id":"https:\/\/www.safes.so\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage"},"image":{"@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage"},"thumbnailUrl":"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg","datePublished":"2023-02-19T15:39:00+00:00","dateModified":"2023-07-25T08:44:00+00:00","description":"Ever wonder why your ancestors\u2019 method of hitting their children didn\u2019t work? Here\u2019s why, along with ways to discipline a child without hitting them.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.safes.so\/de\/blogs\/discipline-a-child-without-hitting\/#primaryimage","url":"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg","contentUrl":"https:\/\/www.safes.so\/wp-content\/uploads\/2023\/02\/Ways-to-discipline-a-child-without-hitting.jpg","width":1200,"height":600,"caption":"Little girl crying on the floor"},{"@type":"WebSite","@id":"https:\/\/www.safes.so\/de\/#website","url":"https:\/\/www.safes.so\/de\/","name":"Screentime Monitoring | Safes Parental Control App","description":"","publisher":{"@id":"https:\/\/www.safes.so\/de\/#organization"},"alternateName":"Safes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.safes.so\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.safes.so\/de\/#organization","name":"Safes Parental Control App","alternateName":"Safes","url":"https:\/\/www.safes.so\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.safes.so\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.safes.so\/wp-content\/uploads\/2022\/06\/11.webp","contentUrl":"https:\/\/www.safes.so\/wp-content\/uploads\/2022\/06\/11.webp","width":240,"height":240,"caption":"Safes Parental Control App"},"image":{"@id":"https:\/\/www.safes.so\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/safesfamily","https:\/\/www.linkedin.com\/company\/safesparentalcontrol\/","https:\/\/www.youtube.com\/@SafesApp"]},{"@type":"Person","@id":"https:\/\/www.safes.so\/de\/#\/schema\/person\/64b618a9ae4e2564f5be7ee8f5308a68","name":"Mahsa Naseri","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.safes.so\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a4c96c3c2a06eab858a973b582c68a87?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4c96c3c2a06eab858a973b582c68a87?s=96&d=mm&r=g","caption":"Mahsa Naseri"}}]}},"_links":{"self":[{"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/posts\/11842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/comments?post=11842"}],"version-history":[{"count":4,"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/posts\/11842\/revisions"}],"predecessor-version":[{"id":20227,"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/posts\/11842\/revisions\/20227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/media\/11583"}],"wp:attachment":[{"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/media?parent=11842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/categories?post=11842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.safes.so\/de\/wp-json\/wp\/v2\/tags?post=11842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}